{"id":4,"count":14,"description":"Cuidados, Higiene y Enfermedades del perro. Viajar con tu perro. Asegurar a tu perro","link":"https:\/\/www.adiestradorcanino.com\/webdelperro\/category\/cuidados-higiene-y-enfermedades\/","name":"Cuidados, Higiene y Enfermedades del perro","slug":"cuidados-higiene-y-enfermedades","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/www.adiestradorcanino.com\/webdelperro\/wp-json\/wp\/v2\/categories\/4","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.adiestradorcanino.com\/webdelperro\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/www.adiestradorcanino.com\/webdelperro\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/www.adiestradorcanino.com\/webdelperro\/wp-json\/wp\/v2\/posts?categories=4"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}